{"id":108,"count":15,"description":"","link":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/","name":"Animal","slug":"animal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/\" \/>\n<meta property=\"og:site_name\" content=\"Best Boarding School in Dehradun | Top Residential Schools for Boys\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2084\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/\",\"name\":\"Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys\",\"isPartOf\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colbrownschool.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#website\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/\",\"name\":\"Col Brown Cambridge School\",\"description\":\"Top Residential School\",\"publisher\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#organization\"},\"alternateName\":\"Col Brown Cambridge School\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colbrownschool.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#organization\",\"name\":\"Best Boarding School In Dehradun | Top Residential School\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png\",\"contentUrl\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png\",\"width\":2084,\"height\":418,\"caption\":\"Best Boarding School In Dehradun | Top Residential School\"},\"image\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/","og_locale":"en_US","og_type":"article","og_title":"Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys","og_url":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/","og_site_name":"Best Boarding School in Dehradun | Top Residential Schools for Boys","og_image":[{"width":2084,"height":418,"url":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/","url":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/","name":"Animal Archives | Best Boarding School in Dehradun | Top Residential Schools for Boys","isPartOf":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.colbrownschool.com\/blog\/tag\/animal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colbrownschool.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Animal"}]},{"@type":"WebSite","@id":"https:\/\/www.colbrownschool.com\/blog\/#website","url":"https:\/\/www.colbrownschool.com\/blog\/","name":"Col Brown Cambridge School","description":"Top Residential School","publisher":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#organization"},"alternateName":"Col Brown Cambridge School","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colbrownschool.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colbrownschool.com\/blog\/#organization","name":"Best Boarding School In Dehradun | Top Residential School","url":"https:\/\/www.colbrownschool.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png","contentUrl":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png","width":2084,"height":418,"caption":"Best Boarding School In Dehradun | Top Residential School"},"image":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/tags\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/posts?tags=108"},{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/tribe_events?tags=108"},{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/tec_calendar_embed?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}