{"id":9366,"date":"2024-11-13T07:55:57","date_gmt":"2024-11-13T07:55:57","guid":{"rendered":"https:\/\/www.colbrownschool.com\/blog\/?p=9366"},"modified":"2024-11-27T06:42:33","modified_gmt":"2024-11-27T06:42:33","slug":"col-brown-cambridge-school-top-icse-residential-school-in-dehradun","status":"publish","type":"post","link":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/","title":{"rendered":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":9367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun","_yoast_wpseo_metadesc":"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India's best residential schools.","_yoast_wpseo_content_score":"30","gdlr-core-page-option":null,"_yoast_wpseo_primary_category":"3","footnotes":""},"categories":[3],"tags":[],"class_list":["post-9366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Col. Brown Cambridge School: Top ICSE Residential School in Dehradun<\/title>\n<meta name=\"description\" content=\"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India&#039;s best residential schools.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun\" \/>\n<meta property=\"og:description\" content=\"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India&#039;s best residential schools.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\" \/>\n<meta property=\"og:site_name\" content=\"Best Boarding School in Dehradun | Top Residential Schools for Boys\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-13T07:55:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T06:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"seoteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"seoteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\"},\"author\":{\"name\":\"seoteam\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/72cacf2c4ace4f52c6d2b6ac89d5131b\"},\"headline\":\"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun\",\"datePublished\":\"2024-11-13T07:55:57+00:00\",\"dateModified\":\"2024-11-27T06:42:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\",\"name\":\"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun\",\"isPartOf\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png\",\"datePublished\":\"2024-11-13T07:55:57+00:00\",\"dateModified\":\"2024-11-27T06:42:33+00:00\",\"description\":\"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India's best residential schools.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png\",\"contentUrl\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colbrownschool.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#website\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/\",\"name\":\"Col Brown Cambridge School\",\"description\":\"Top Residential School\",\"publisher\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#organization\"},\"alternateName\":\"Col Brown Cambridge School\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colbrownschool.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#organization\",\"name\":\"Best Boarding School In Dehradun | Top Residential School\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png\",\"contentUrl\":\"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png\",\"width\":2084,\"height\":418,\"caption\":\"Best Boarding School In Dehradun | Top Residential School\"},\"image\":{\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/72cacf2c4ace4f52c6d2b6ac89d5131b\",\"name\":\"seoteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/826c2497a772715c5094a33e48ec2229cc04207717d4f22f739d76571dffcebe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/826c2497a772715c5094a33e48ec2229cc04207717d4f22f739d76571dffcebe?s=96&d=mm&r=g\",\"caption\":\"seoteam\"},\"url\":\"https:\/\/www.colbrownschool.com\/blog\/author\/seoteam\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun","description":"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India's best residential schools.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/","og_locale":"en_US","og_type":"article","og_title":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun","og_description":"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India's best residential schools.","og_url":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/","og_site_name":"Best Boarding School in Dehradun | Top Residential Schools for Boys","article_published_time":"2024-11-13T07:55:57+00:00","article_modified_time":"2024-11-27T06:42:33+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png","type":"image\/png"}],"author":"seoteam","twitter_card":"summary_large_image","twitter_misc":{"Written by":"seoteam","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#article","isPartOf":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/"},"author":{"name":"seoteam","@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/72cacf2c4ace4f52c6d2b6ac89d5131b"},"headline":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun","datePublished":"2024-11-13T07:55:57+00:00","dateModified":"2024-11-27T06:42:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/","url":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/","name":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun","isPartOf":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage"},"image":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png","datePublished":"2024-11-13T07:55:57+00:00","dateModified":"2024-11-27T06:42:33+00:00","description":"Col. Brown Cambridge School in Dehradun offers top-tier ICSE education, holistic development, and affordable boarding, making it one of India's best residential schools.","breadcrumb":{"@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#primaryimage","url":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png","contentUrl":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2024\/11\/image_2024_11_12T07_51_18_658Z.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.colbrownschool.com\/blog\/col-brown-cambridge-school-top-icse-residential-school-in-dehradun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colbrownschool.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Col. Brown Cambridge School: Top ICSE Residential School in Dehradun"}]},{"@type":"WebSite","@id":"https:\/\/www.colbrownschool.com\/blog\/#website","url":"https:\/\/www.colbrownschool.com\/blog\/","name":"Col Brown Cambridge School","description":"Top Residential School","publisher":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#organization"},"alternateName":"Col Brown Cambridge School","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colbrownschool.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.colbrownschool.com\/blog\/#organization","name":"Best Boarding School In Dehradun | Top Residential School","url":"https:\/\/www.colbrownschool.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png","contentUrl":"https:\/\/www.colbrownschool.com\/blog\/wp-content\/uploads\/2022\/08\/col-brown-school-logo.png","width":2084,"height":418,"caption":"Best Boarding School In Dehradun | Top Residential School"},"image":{"@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/72cacf2c4ace4f52c6d2b6ac89d5131b","name":"seoteam","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.colbrownschool.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/826c2497a772715c5094a33e48ec2229cc04207717d4f22f739d76571dffcebe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/826c2497a772715c5094a33e48ec2229cc04207717d4f22f739d76571dffcebe?s=96&d=mm&r=g","caption":"seoteam"},"url":"https:\/\/www.colbrownschool.com\/blog\/author\/seoteam\/"}]}},"builder_content":"","_links":{"self":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/posts\/9366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/comments?post=9366"}],"version-history":[{"count":5,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/posts\/9366\/revisions"}],"predecessor-version":[{"id":9414,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/posts\/9366\/revisions\/9414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/media\/9367"}],"wp:attachment":[{"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/media?parent=9366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/categories?post=9366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colbrownschool.com\/blog\/wp-json\/wp\/v2\/tags?post=9366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}